{"id":3070,"date":"2021-11-22T16:54:28","date_gmt":"2021-11-22T16:54:28","guid":{"rendered":"https:\/\/iberogen.com\/product\/pack-analisis-coccidios-megabacteria\/"},"modified":"2024-02-06T18:26:56","modified_gmt":"2024-02-06T18:26:56","slug":"pack-detection-de-coccidies-megabacteriose","status":"publish","type":"product","link":"https:\/\/iberogen.com\/fr\/produit\/pack-detection-de-coccidies-megabacteriose\/","title":{"rendered":"Pack test f\u00e9cal pour oiseaux : d\u00e9tection de Coccidies + M\u00e9gabact\u00e9riose"},"content":{"rendered":"<p>Analyse microscopique des oocystes de coccidies + Analyse microscopique pour la d\u00e9tection de <em>Macrorhabdus ornithogaster<\/em> (m\u00e9gabact\u00e9rie) dans des \u00e9chantillons de selles fra\u00eeches.<\/p>\n<p><strong>\u00c9chantillons \u00e0 analyser: \u00e9chantillon de selles.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Analyse microscopique des oocystes de coccidies + Analyse microscopique pour la d\u00e9tection de Macrorhabdus ornithogaster (m\u00e9gabact\u00e9rie) dans des \u00e9chantillons de selles fra\u00eeches. \u00c9chantillons \u00e0 analyser: \u00e9chantillon de selles.<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[1500,1493],"product_tag":[],"tipo_de_muestra":[1511],"especie":[1527],"class_list":["post-3070","product","type-product","status-publish","product_cat-analyse-fecale-chez-les-oiseaux","product_cat-veterinaire","first","instock","shipping-taxable","purchasable","product-type-variable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pack d&#039;analyse Coccidies + M\u00e9gabact\u00e9ries | Iberogen<\/title>\n<meta name=\"description\" content=\"Commandez en ligne notre service pack d&#039;analyse Coccidies + M\u00e9gabact\u00e9ries. Visitez notre boutique en ligne et d\u00e9couvrez tous nos services.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/iberogen.com\/fr\/produit\/pack-detection-de-coccidies-megabacteriose\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pack d&#039;analyse Coccidies + M\u00e9gabact\u00e9ries | Iberogen\" \/>\n<meta property=\"og:description\" content=\"Commandez en ligne notre service pack d&#039;analyse Coccidies + M\u00e9gabact\u00e9ries. Visitez notre boutique en ligne et d\u00e9couvrez tous nos services.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/iberogen.com\/fr\/produit\/pack-detection-de-coccidies-megabacteriose\/\" \/>\n<meta property=\"og:site_name\" content=\"Iberogen\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-06T18:26:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/iberogen.com\/fr\/produit\/pack-detection-de-coccidies-megabacteriose\/\",\"url\":\"https:\/\/iberogen.com\/fr\/produit\/pack-detection-de-coccidies-megabacteriose\/\",\"name\":\"Pack d'analyse Coccidies + M\u00e9gabact\u00e9ries | Iberogen\",\"isPartOf\":{\"@id\":\"https:\/\/iberogen.com\/fr\/#website\"},\"datePublished\":\"2021-11-22T16:54:28+00:00\",\"dateModified\":\"2024-02-06T18:26:56+00:00\",\"description\":\"Commandez en ligne notre service pack d'analyse Coccidies + M\u00e9gabact\u00e9ries. Visitez notre boutique en ligne et d\u00e9couvrez tous nos services.\",\"breadcrumb\":{\"@id\":\"https:\/\/iberogen.com\/fr\/produit\/pack-detection-de-coccidies-megabacteriose\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/iberogen.com\/fr\/produit\/pack-detection-de-coccidies-megabacteriose\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/iberogen.com\/fr\/produit\/pack-detection-de-coccidies-megabacteriose\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/iberogen.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\/\/iberogen.com\/fr\/boutique\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pack test f\u00e9cal pour oiseaux : d\u00e9tection de Coccidies + M\u00e9gabact\u00e9riose\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/iberogen.com\/fr\/#website\",\"url\":\"https:\/\/iberogen.com\/fr\/\",\"name\":\"Iberogen\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/iberogen.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pack d'analyse Coccidies + M\u00e9gabact\u00e9ries | Iberogen","description":"Commandez en ligne notre service pack d'analyse Coccidies + M\u00e9gabact\u00e9ries. Visitez notre boutique en ligne et d\u00e9couvrez tous nos services.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/iberogen.com\/fr\/produit\/pack-detection-de-coccidies-megabacteriose\/","og_locale":"fr_FR","og_type":"article","og_title":"Pack d'analyse Coccidies + M\u00e9gabact\u00e9ries | Iberogen","og_description":"Commandez en ligne notre service pack d'analyse Coccidies + M\u00e9gabact\u00e9ries. Visitez notre boutique en ligne et d\u00e9couvrez tous nos services.","og_url":"https:\/\/iberogen.com\/fr\/produit\/pack-detection-de-coccidies-megabacteriose\/","og_site_name":"Iberogen","article_modified_time":"2024-02-06T18:26:56+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/iberogen.com\/fr\/produit\/pack-detection-de-coccidies-megabacteriose\/","url":"https:\/\/iberogen.com\/fr\/produit\/pack-detection-de-coccidies-megabacteriose\/","name":"Pack d'analyse Coccidies + M\u00e9gabact\u00e9ries | Iberogen","isPartOf":{"@id":"https:\/\/iberogen.com\/fr\/#website"},"datePublished":"2021-11-22T16:54:28+00:00","dateModified":"2024-02-06T18:26:56+00:00","description":"Commandez en ligne notre service pack d'analyse Coccidies + M\u00e9gabact\u00e9ries. Visitez notre boutique en ligne et d\u00e9couvrez tous nos services.","breadcrumb":{"@id":"https:\/\/iberogen.com\/fr\/produit\/pack-detection-de-coccidies-megabacteriose\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/iberogen.com\/fr\/produit\/pack-detection-de-coccidies-megabacteriose\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/iberogen.com\/fr\/produit\/pack-detection-de-coccidies-megabacteriose\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/iberogen.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/iberogen.com\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"Pack test f\u00e9cal pour oiseaux : d\u00e9tection de Coccidies + M\u00e9gabact\u00e9riose"}]},{"@type":"WebSite","@id":"https:\/\/iberogen.com\/fr\/#website","url":"https:\/\/iberogen.com\/fr\/","name":"Iberogen","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/iberogen.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/iberogen.com\/fr\/wp-json\/wp\/v2\/product\/3070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iberogen.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/iberogen.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/iberogen.com\/fr\/wp-json\/wp\/v2\/media?parent=3070"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/iberogen.com\/fr\/wp-json\/wp\/v2\/product_brand?post=3070"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/iberogen.com\/fr\/wp-json\/wp\/v2\/product_cat?post=3070"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/iberogen.com\/fr\/wp-json\/wp\/v2\/product_tag?post=3070"},{"taxonomy":"tipo_de_muestra","embeddable":true,"href":"https:\/\/iberogen.com\/fr\/wp-json\/wp\/v2\/tipo_de_muestra?post=3070"},{"taxonomy":"especie","embeddable":true,"href":"https:\/\/iberogen.com\/fr\/wp-json\/wp\/v2\/especie?post=3070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}